{"id":8624,"date":"2026-05-12T13:53:09","date_gmt":"2026-05-12T16:53:09","guid":{"rendered":"https:\/\/oroverde.gob.ar\/portal\/?p=8624"},"modified":"2026-05-12T13:53:09","modified_gmt":"2026-05-12T16:53:09","slug":"muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo","status":"publish","type":"post","link":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/","title":{"rendered":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo"},"content":{"rendered":"<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\">Integrantes del proyecto art\u00edstico municipal \u201cNuestros trazos, nuestros verdes\u00bb representaron a Oro Verde en el 4to Encuentro Provincial de Muralismo en Maci\u00e1 el pasado s\u00e1bado. Asistieron Emilce Faes, Zamira Efchi, Celeste Sauthier y Justina Marengo por el \u00e1rea de Cultura municipal.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Los artistas participaron de intensas instancias de formaci\u00f3n y trabajo de campo, reafirmando el compromiso con el arte p\u00fablico y la identidad regional.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La delegaci\u00f3n form\u00f3 parte de la capacitaci\u00f3n denominada \u00abMurales con tiempo propio: Ideas para antes y despu\u00e9s de la pared\u00bb coordinada por Camila Guerra, conocida art\u00edsticamente como \u00abChina del R\u00edo\u00bb. En este espacio se abord\u00f3 el muralismo no s\u00f3lo como una t\u00e9cnica pict\u00f3rica, sino como un proceso de planificaci\u00f3n estrat\u00e9gica y preservaci\u00f3n de la obra en el tiempo.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Adem\u00e1s, las artistas se sumaron al Taller de Mural Comunitario y Participativo dictado por la referente paranaense Florencia Albornoz. Esta actividad tuvo como eje central la aproximaci\u00f3n al muralismo como una herramienta de vinculaci\u00f3n con la comunidad.<\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">La experiencia pr\u00e1ctica se llev\u00f3 a cabo en el pared\u00f3n de la Escuela Jos\u00e9 M. Paz, donde el conocimiento te\u00f3rico se transform\u00f3 en acci\u00f3n colectiva dejando una huella visual en una de las instituciones emblem\u00e1ticas de Maci\u00e1.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes del proyecto art\u00edstico municipal \u201cNuestros trazos, nuestros verdes\u00bb representaron a Oro Verde en el 4to Encuentro Provincial de Muralismo en Maci\u00e1 el pasado s\u00e1bado. Asistieron Emilce Faes, Zamira Efchi, Celeste Sauthier y Justina Marengo por el \u00e1rea de Cultura municipal. Los artistas &hellip;<\/p>\n","protected":false},"author":3,"featured_media":8625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-8624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde\" \/>\n<meta property=\"og:description\" content=\"Integrantes del proyecto art\u00edstico municipal \u201cNuestros trazos, nuestros verdes\u00bb representaron a Oro Verde en el 4to Encuentro Provincial de Muralismo en Maci\u00e1 el pasado s\u00e1bado. Asistieron Emilce Faes, Zamira Efchi, Celeste Sauthier y Justina Marengo por el \u00e1rea de Cultura municipal. Los artistas &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Municipio de Oro Verde\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T16:53:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Soledad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Soledad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/\"},\"author\":{\"name\":\"Soledad\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#\\\/schema\\\/person\\\/b975e0cbcd43b7dcf9c64511ec84f10f\"},\"headline\":\"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo\",\"datePublished\":\"2026-05-12T16:53:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/muralistas.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/\",\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/\",\"name\":\"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/muralistas.jpg\",\"datePublished\":\"2026-05-12T16:53:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/muralistas.jpg\",\"contentUrl\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/muralistas.jpg\",\"width\":799,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/\",\"name\":\"Municipio de Oro Verde\",\"description\":\"Web Oficial\",\"publisher\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#organization\",\"name\":\"Municipio de Oro Verde\",\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-cropped-logo-1.png\",\"width\":1776,\"height\":738,\"caption\":\"Municipio de Oro Verde\"},\"image\":{\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/#\\\/schema\\\/person\\\/b975e0cbcd43b7dcf9c64511ec84f10f\",\"name\":\"Soledad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g\",\"caption\":\"Soledad\"},\"url\":\"https:\\\/\\\/oroverde.gob.ar\\\/portal\\\/author\\\/soledad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/","og_locale":"es_ES","og_type":"article","og_title":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde","og_description":"Integrantes del proyecto art\u00edstico municipal \u201cNuestros trazos, nuestros verdes\u00bb representaron a Oro Verde en el 4to Encuentro Provincial de Muralismo en Maci\u00e1 el pasado s\u00e1bado. Asistieron Emilce Faes, Zamira Efchi, Celeste Sauthier y Justina Marengo por el \u00e1rea de Cultura municipal. Los artistas &hellip;","og_url":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/","og_site_name":"Municipio de Oro Verde","article_published_time":"2026-05-12T16:53:09+00:00","og_image":[{"width":799,"height":533,"url":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg","type":"image\/jpeg"}],"author":"Soledad","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Soledad","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#article","isPartOf":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/"},"author":{"name":"Soledad","@id":"https:\/\/oroverde.gob.ar\/portal\/#\/schema\/person\/b975e0cbcd43b7dcf9c64511ec84f10f"},"headline":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo","datePublished":"2026-05-12T16:53:09+00:00","mainEntityOfPage":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/"},"wordCount":228,"publisher":{"@id":"https:\/\/oroverde.gob.ar\/portal\/#organization"},"image":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#primaryimage"},"thumbnailUrl":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg","articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/","url":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/","name":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo - Municipio de Oro Verde","isPartOf":{"@id":"https:\/\/oroverde.gob.ar\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#primaryimage"},"image":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#primaryimage"},"thumbnailUrl":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg","datePublished":"2026-05-12T16:53:09+00:00","breadcrumb":{"@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#primaryimage","url":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg","contentUrl":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2026\/05\/muralistas.jpg","width":799,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/oroverde.gob.ar\/portal\/muralistas-oroverdenses-participaron-de-4to-encuentro-provincial-de-muralismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oroverde.gob.ar\/portal\/"},{"@type":"ListItem","position":2,"name":"Muralistas oroverdenses participaron de 4to Encuentro Provincial de Muralismo"}]},{"@type":"WebSite","@id":"https:\/\/oroverde.gob.ar\/portal\/#website","url":"https:\/\/oroverde.gob.ar\/portal\/","name":"Municipio de Oro Verde","description":"Web Oficial","publisher":{"@id":"https:\/\/oroverde.gob.ar\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oroverde.gob.ar\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oroverde.gob.ar\/portal\/#organization","name":"Municipio de Oro Verde","url":"https:\/\/oroverde.gob.ar\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oroverde.gob.ar\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2024\/06\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/oroverde.gob.ar\/portal\/wp-content\/uploads\/2024\/06\/cropped-cropped-logo-1.png","width":1776,"height":738,"caption":"Municipio de Oro Verde"},"image":{"@id":"https:\/\/oroverde.gob.ar\/portal\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oroverde.gob.ar\/portal\/#\/schema\/person\/b975e0cbcd43b7dcf9c64511ec84f10f","name":"Soledad","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2f5b6cda565395f31dc94c95932b9b3fbe6275bad58a1579843d3d1607d4a66?s=96&d=mm&r=g","caption":"Soledad"},"url":"https:\/\/oroverde.gob.ar\/portal\/author\/soledad\/"}]}},"_links":{"self":[{"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/posts\/8624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/comments?post=8624"}],"version-history":[{"count":1,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/posts\/8624\/revisions"}],"predecessor-version":[{"id":8626,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/posts\/8624\/revisions\/8626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/media\/8625"}],"wp:attachment":[{"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/media?parent=8624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/categories?post=8624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oroverde.gob.ar\/portal\/wp-json\/wp\/v2\/tags?post=8624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}